{"id":10067,"date":"2016-02-13T08:00:04","date_gmt":"2016-02-13T13:00:04","guid":{"rendered":"https:\/\/emisora.univalle.edu.co\/\/?p=10067"},"modified":"2016-02-12T15:27:58","modified_gmt":"2016-02-12T20:27:58","slug":"estudiantes-de-cobertura-reciben-tarjetas-del-mio","status":"publish","type":"post","link":"https:\/\/emisora.univalle.edu.co\/index.php\/estudiantes-de-cobertura-reciben-tarjetas-del-mio\/","title":{"rendered":"Estudiantes de cobertura reciben tarjetas del MIO"},"content":{"rendered":"<p><span style=\"line-height: 1.5em;\">Los martes y jueves en la Central Did\u00e1ctica, ubicada en la calle 27 No 36-10 del barrio El Jard\u00edn, a los padres de familia que tienen hijos reubicados por cobertura educativa en bachillerato, se les hace entrega de tarjetas del MIO para que ellos se desplacen a estudiar gratuitamente durante 160 d\u00edas calendario y as\u00ed compensen el tener que ir a estudiar a una instituci\u00f3n educativa distante de su casa.<\/span><\/p>\n<p>Los requisitos para acceder a este beneficio, son:<\/p>\n<p>\u2022 Los padres del estudiante deben tener Sisb\u00e9n 1 \u00f3 2<\/p>\n<p>\u2022 Pertenecer a los estratos 1 \u00f3 2<\/p>\n<p>\u2022 Estudiar en una instituci\u00f3n educativa oficial<\/p>\n<p>\u2022 Anexar certificaci\u00f3n de matr\u00edcula original expedido por la instituci\u00f3n educativa donde est\u00e1 matriculado, la cual debe pertenecer a las comunas catalogadas como deficitarias, es decir donde no hay cupos y el estudiante se debe desplazar desde otros barrios para llegar a su instituci\u00f3n.<\/p>\n<p>Seg\u00fan inform\u00f3 la funcionaria de Acceso y Permanencia, Paola Rivera, estas tarjetas tienen una duraci\u00f3n de aproximadamente 160 d\u00edas calendarios, esto con el fin de tener la posibilidad de hacer seguimiento de la permanencia del ni\u00f1o en el sistema escolar, pero estas se renuevan cuando el saldo se acaba y solo pueden ser utilizadas por el estudiante en el horario de su jornada escolar.<\/p>\n<p>La Secretaria de Educaci\u00f3n, Luz Elena Azc\u00e1rate, se sinti\u00f3 complacida con la asistencia de los padres de familia para reclamar este auxilio de transporte, representado en la tarjeta MIO, en especial de los ni\u00f1os reubicados de colegios que no cumpl\u00edan con el percentil 20 y que fueron asignados a nuevas instituciones educativas oficiales, lo cual garantizar\u00e1 que su asistencia a clases no se vea interrumpida por haber cambiado de colegio, ya que la Secretar\u00eda de Educaci\u00f3n les proporciona el traslado en el transporte MIO de manera gratuita.<\/p>\n<p>Fuente: Comunicaciones Alcald\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los martes y jueves en la Central Did\u00e1ctica, ubicada en la calle 27 No 36-10 del barrio El Jard\u00edn, a los padres de familia que tienen hijos reubicados por cobertura educativa en bachillerato, se les hace entrega de tarjetas del MIO para que ellos se desplacen a estudiar gratuitamente durante[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":10030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/10067"}],"collection":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=10067"}],"version-history":[{"count":1,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/10067\/revisions"}],"predecessor-version":[{"id":10070,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/10067\/revisions\/10070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media\/10030"}],"wp:attachment":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=10067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=10067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=10067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}