{"id":10111,"date":"2016-02-15T14:54:38","date_gmt":"2016-02-15T19:54:38","guid":{"rendered":"https:\/\/emisora.univalle.edu.co\/\/?p=10111"},"modified":"2016-02-15T14:54:38","modified_gmt":"2016-02-15T19:54:38","slug":"armitage-anuncio-construccion-de-10-megacolegios","status":"publish","type":"post","link":"https:\/\/emisora.univalle.edu.co\/index.php\/armitage-anuncio-construccion-de-10-megacolegios\/","title":{"rendered":"Armitage anunci\u00f3 construcci\u00f3n de 10 megacolegios"},"content":{"rendered":"<p><span style=\"line-height: 1.5em;\">Una gran necesidad de apoyo en educaci\u00f3n, cultura, y recreaci\u00f3n ha percibido el alcalde de Cali, Maurice Armitage, durante los 12 encuentros que ha sostenido con la comunidad.<\/span><\/p>\n<p>Por eso durante su gobierno espera construir 10 megacolegios de jornada escolar continua, donde se les proporcione a los alumnos todos estos ingredientes fundamentales para el desarrollo integral. \u201cVoy a solicitarle al presidente del BID, Alberto Moreno que nos visita hoy, apoyo.<\/p>\n<p>\u201cEsperamos hacer una inversi\u00f3n de un bill\u00f3n de pesos y construir por lo menos 10 megacolegios; el municipio pondr\u00e1 cerca de 300 mil millones y que la naci\u00f3n nos ayude con $600 mil millones\u201d. El anuncio lo hizo en el CALI 10 del barrio El Guabal, donde l\u00edderes del sector le expusieron las principales necesidades de los barrios que conforman la comuna.<\/p>\n<p>Otra buena noticia tiene que ver con la cuadrilla de trabajadores que llegar\u00e1 a arreglar las v\u00edas de la comuna 10 de Cali, tal como se lo solicitaron los l\u00edderes, \u201cAl igual que la comuna 6, la 10 va a tener una cuadrilla, nosotros vamos a empezar con la Secretar\u00eda de Infraestructura a asignar y destinar esas cuadrillas para que ellos empiecen a trabajar\u201d, puntualiz\u00f3 el mandatario cale\u00f1o.<\/p>\n<p>La comunidad en condici\u00f3n de discapacidad quiz\u00e1s es la \u00fanica que est\u00e1 caracterizada y censada. Solicitaron al gobierno local ayuda en temas de emprendimiento y educaci\u00f3n especial, para quienes ellos llaman personas con capacidades especiales. \u201cSon 554 personas con capacidades diferentes entre los 3 y 99 a\u00f1os, todos censados y caracterizados, que necesitan apoyo del gobierno\u201d, expres\u00f3 Vilma Ort\u00edz.<\/p>\n<p>El mandatario cale\u00f1o anunci\u00f3 apoyo para esta poblaci\u00f3n y recursos para programas de desarrollo por el orden de $130 millones, adem\u00e1s en trabajo articulado de todas las secretar\u00edas para apoyar los programas.<\/p>\n<p>Julio Camacho es uno de los l\u00edderes que pidi\u00f3 ayuda en el tema de seguridad, dijo que el corredor de la galer\u00eda Santa Elena requiere especial atenci\u00f3n y que la polic\u00eda necesita apoyo log\u00edstico para fortalecer los cuadrantes de seguridad. \u201cLa galer\u00eda Santa Elena es prioridad no solo del sector, es b\u00e1sica para todo Cali, tenemos que solucionar la seguridad y el impacto ambiental\u201d, puntualiz\u00f3 el Alcalde, a\u00f1adi\u00f3 que actualmente la Polic\u00eda est\u00e1 haciendo un inventario general de sus necesidades, para as\u00ed la Alcald\u00eda hacer un presupuesto donde se le d\u00e9 prioridad a las m\u00e1s urgentes.<\/p>\n<p>Finalmente el mandatario cale\u00f1o dijo que espera hacer 46 visitas a las comunas, donde se les solucione necesidades urgentes a los cale\u00f1os.<\/p>\n<p>Fuente: <a href=\"http:\/\/cali.gov.co\">Comunicaciones Alcald\u00eda<\/a><\/p>\n<p><a href=\"http:\/\/cali.gov.co\">\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una gran necesidad de apoyo en educaci\u00f3n, cultura, y recreaci\u00f3n ha percibido el alcalde de Cali, Maurice Armitage, durante los 12 encuentros que ha sostenido con la comunidad. Por eso durante su gobierno espera construir 10 megacolegios de jornada escolar continua, donde se les proporcione a los alumnos todos estos[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":10101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/10111"}],"collection":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=10111"}],"version-history":[{"count":1,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/10111\/revisions"}],"predecessor-version":[{"id":10112,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/10111\/revisions\/10112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media\/10101"}],"wp:attachment":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=10111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=10111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=10111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}