{"id":16545,"date":"2016-11-09T15:18:38","date_gmt":"2016-11-09T20:18:38","guid":{"rendered":"https:\/\/emisora.univalle.edu.co\/?p=16545"},"modified":"2016-11-09T15:18:38","modified_gmt":"2016-11-09T20:18:38","slug":"hoy-se-inaugura-cine-foro-andres-caicedo","status":"publish","type":"post","link":"https:\/\/emisora.univalle.edu.co\/index.php\/hoy-se-inaugura-cine-foro-andres-caicedo\/","title":{"rendered":"Hoy se inaugura el Cine Foro Andr\u00e9s Caicedo"},"content":{"rendered":"<p>Con una inversi\u00f3n de $ 40 millones de pesos y con la finalidad de impulsar las producciones locales e incentivar el desarrollo de la industria cinematogr\u00e1fica del Valle del Cauca, la Alcald\u00eda de Cali, a trav\u00e9s de la Secretar\u00eda de Cultura y Turismo, inaugura hoy la programaci\u00f3n del Cine Foro Andr\u00e9s Caicedo, rindiendo de esta manera tributo a este cale\u00f1o, figura del cine y las letras.<\/p>\n<p>El acto se cumplir\u00e1 a partir de las 7:00 de la noche, en las instalaciones del Cine Foro, en el segundo piso de la Plazoleta Jairo Varela.<\/p>\n<p>As\u00ed lo dio a conocer Luz Adriana Betancourt, titular de la dependencia en el acto de presentaci\u00f3n de la programaci\u00f3n oficial del Festival Internacional de Cine de Cali.<\/p>\n<p>La Secretaria de Cultura y los Estudios de Grabaci\u00f3n Takeshima son las organizadoras del evento que va desde el 10 hasta el 14 de noviembre.<\/p>\n<p>\u201cCon el consentimiento de la familia de Andr\u00e9s Caicedo, tendremos los fines de semana, la programaci\u00f3n de realizaciones cale\u00f1as y nacionales, en la sala concebida y debidamente dotada para ello, en el segundo piso de la Plazoleta Jairo Varela\u201d, indic\u00f3.<\/p>\n<p>Pilar Caicedo, al referirse a este reconocimiento, indic\u00f3 que para la familia es muy importante que la memoria de su hermano se mantenga vigente, mas con un cine foro; ya que esto fue una de las paciones que tuvo a los largo de su vida, desde su creaci\u00f3n de \u2018Ojo al Cine\u2019.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una inversi\u00f3n de $ 40 millones de pesos y con la finalidad de impulsar las producciones locales e incentivar el desarrollo de la industria cinematogr\u00e1fica del Valle del Cauca, la Alcald\u00eda de Cali, a trav\u00e9s de la Secretar\u00eda de Cultura y Turismo, inaugura hoy la programaci\u00f3n del Cine Foro[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":16547,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/16545"}],"collection":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=16545"}],"version-history":[{"count":1,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/16545\/revisions"}],"predecessor-version":[{"id":16548,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/16545\/revisions\/16548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media\/16547"}],"wp:attachment":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=16545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=16545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=16545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}