{"id":16557,"date":"2016-11-10T09:31:19","date_gmt":"2016-11-10T14:31:19","guid":{"rendered":"https:\/\/emisora.univalle.edu.co\/?p=16557"},"modified":"2016-11-10T09:31:19","modified_gmt":"2016-11-10T14:31:19","slug":"cali-conmemorara-la-no-violencia-hacia-las-mujeres","status":"publish","type":"post","link":"https:\/\/emisora.univalle.edu.co\/index.php\/cali-conmemorara-la-no-violencia-hacia-las-mujeres\/","title":{"rendered":"Cali conmemorar\u00e1 la no violencia hacia las mujeres"},"content":{"rendered":"<p>La Alcald\u00eda de Santiago de Cali, en su compromiso por la reivindicaci\u00f3n de los Derechos de las mujeres, realiza el lanzamiento de la campa\u00f1a \u201cTodas las Mujeres, todos los derechos\u201d la cual pretende visibilizar las diferentes posibilidades de participaci\u00f3n de las mujeres, generando espacios de reflexi\u00f3n que permitan el reconocimiento de las diversas formas de relaci\u00f3n con lo individual, social y cultural.<\/p>\n<p>Esta campa\u00f1a es realizada por la Mesa interinstitucional para la erradicaci\u00f3n de las violencias y la implementaci\u00f3n de la Pol\u00edtica P\u00fablica para las mujeres en la ciudad de Cali, en la cual confluyen las Secretar\u00edas de Bienestar Social, Cultura y turismo, Salud p\u00fablica, Educaci\u00f3n y Deporte; as\u00ed como las Asesor\u00edas de Paz, Telem\u00e1tica y la Asesor\u00eda de Equidad de G\u00e9nero que coordina la mesa t\u00e9cnica.<\/p>\n<p>Durante todo noviembre se adelantar\u00e1n diferentes actos conmemorativos\u00a0 y actividades en torno al D\u00eda Internacional de la No violencias hacia las Mujeres que permitir\u00e1n la participaci\u00f3n de la comunidad en general.<\/p>\n<p>Estas son las actividades que tienen programadas en este mes, las diferentes dependencias de la Alcald\u00eda de Cali:<\/p>\n<p>Noviembre 14:<\/p>\n<p>Exaltaci\u00f3n\u00a0 del d\u00eda nacional de la mujer Colombiana en las redes sociales de la Administraci\u00f3n Municipal.<\/p>\n<p>Noviembre 15:<\/p>\n<p>Asesor\u00eda de Paz. Encuentro de mujeres y Violencia Sexual en el marco del conflicto armado.<\/p>\n<p>Hora: 8 am a 1pm<\/p>\n<p>&nbsp;<\/p>\n<p>Noviembre 18:<\/p>\n<p>Feria de Servicios por una vida libre de violencias en el territorio.<\/p>\n<p>Lugar: Comuna 15.\u00a0 Parque Olaya carrera 41b entre calle 50 y 51.<\/p>\n<p>Hora: 9 am a 3 pm<\/p>\n<p>Noviembre 23:<\/p>\n<p>Foro \u201cEl Papel de la Educaci\u00f3n en la prevenci\u00f3n de las violencias basadas en g\u00e9nero\u201d.<\/p>\n<p>Lugar: Centro de Capacitaci\u00f3n Don Bosco<\/p>\n<p>Hora: 2 am a 6 pm<\/p>\n<p>Noviembre 24:<\/p>\n<p>Foro abuso sexual a menores en el marco del comit\u00e9 municipal de prevenci\u00f3n y atenci\u00f3n del abuso sexual. Comit\u00e9 de universidades y Secretar\u00eda de Salud, derechos sexuales y reproductivos.<\/p>\n<p>Noviembre 21 a Noviembre 25:<\/p>\n<p>Eventos acad\u00e9micos Secretar\u00eda de Salud en el marco de la semana de salud mental y en la tarde intervenciones comunitarias.<\/p>\n<p>Noviembre 25:<\/p>\n<p>Secretar\u00eda de Desarrollo Territorial y Bienestar Social<\/p>\n<p>Actividades de autocuidado y corporalidad.<\/p>\n<p>Lugar: Casa Matria<\/p>\n<p>Hora: 1 pm a 4 pm<\/p>\n<p>Acto central de Conmemoraci\u00f3n del d\u00eda internacional de la No Violencia contra las mujeres.<\/p>\n<p>Lugar. Plazoleta Jairo Varela<\/p>\n<p>Hora. 3 pm a 6 pm<\/p>\n<p>Secretar\u00eda de Cultura y Turismo<\/p>\n<p>Clausura proceso formaci\u00f3n artes pl\u00e1sticas y esc\u00e9nicas con Mujeres de comunas y corregimientos.<\/p>\n<p>Lugar. Centro Cultural de Cali<\/p>\n<p>Hora. 8 am a 12 am<\/p>\n<p>Noviembre 21 al 25:<\/p>\n<p>Secretar\u00eda de Cultura y Turismo<\/p>\n<p>Actividades de sensibilizaci\u00f3n para la prevenci\u00f3n de las violencias en bibliotecas p\u00fablicas de la ciudad.<\/p>\n<p>Noviembre 26:<\/p>\n<p>Foro. El papel del deporte para la prevenci\u00f3n de las Violencias contra las Mujeres.<\/p>\n<p>Lugar. Por definir<\/p>\n<p>Hora. 2 a 6 pm<\/p>\n<p>Noviembre 29:<\/p>\n<p>Mujeres y\u00a0 Emprendimiento digital TIC<\/p>\n<p>Lugar. Cine Foro- Plazoleta Jairo Varela<\/p>\n<p>Hora. 2 a 6 pm<\/p>\n<p>Noviembre 30:<\/p>\n<p>Balances y ajustes a la pol\u00edtica p\u00fablica de las mujeres en Cali. Avanzando para la garant\u00eda de derechos de las Mujeres.<\/p>\n<p>Lugar. Universidad del Valle- Sede San Fernando<\/p>\n<p>Hora. 2 a 6 pm<\/p>\n<p>Diciembre 4:<\/p>\n<p>Encuentro de Mujeres ind\u00edgenas de los cabildos urbanos de Santiago de Cali.<\/p>\n<p>Fuente: Comunicaciones Alcald\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Alcald\u00eda de Santiago de Cali, en su compromiso por la reivindicaci\u00f3n de los Derechos de las mujeres, realiza el lanzamiento de la campa\u00f1a \u201cTodas las Mujeres, todos los derechos\u201d la cual pretende visibilizar las diferentes posibilidades de participaci\u00f3n de las mujeres, generando espacios de reflexi\u00f3n que permitan el reconocimiento[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":16559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/16557"}],"collection":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/comments?post=16557"}],"version-history":[{"count":1,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/16557\/revisions"}],"predecessor-version":[{"id":16561,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/posts\/16557\/revisions\/16561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media\/16559"}],"wp:attachment":[{"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/media?parent=16557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/categories?post=16557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emisora.univalle.edu.co\/index.php\/wp-json\/wp\/v2\/tags?post=16557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}